{"id":17000,"date":"2022-08-25T10:47:44","date_gmt":"2022-08-25T10:47:44","guid":{"rendered":"https:\/\/t-golf.club\/?page_id=17000"},"modified":"2026-08-14T09:31:31","modified_gmt":"2026-08-14T09:31:31","slug":"golfplatz","status":"publish","type":"page","link":"https:\/\/t-golf.club\/de\/palma\/golfplatz\/","title":{"rendered":"Golfplatz &#8211; T Golf Palma"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":275,"featured_media":16977,"parent":16938,"menu_order":140,"comment_status":"closed","ping_status":"closed","template":"views\/golf-course.blade.php","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-17000","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":{"subtitle":"Ein mediterranes Meisterwerk","video_title":"Golf Course","video_image":16915,"tournament_title":"Turniere","content":"<p><strong>T GOLF PALMA ist ein 18-Loch-Golfplatz mit Par 71, der sich auf einem Gel\u00e4nde von etwa 165 Hektar befindet. Der Schwierigkeitsgrad des Platzes ist durchschnittlich, obwohl er von den hinteren Abschl\u00e4gen aus ein hohes Niveau erreichen kann. Der Platz hat eine Gesamtl\u00e4nge von ca. 6.591 Yards von den wei\u00dfen Abschl\u00e4gen aus, wo L\u00f6cher mit hoher Pr\u00e4zision und L\u00f6cher f\u00fcr gro\u00dfe Abschl\u00e4ge zu sehen sind.<\/strong><\/p>\n<p>Der Platz wurde entsprechend der Topographie des Gel\u00e4ndes angelegt und bringt die nat\u00fcrliche Vegetation aus Kiefern, wilden Olivenb\u00e4umen, Johannisbrotb\u00e4umen und B\u00fcschen ins Spiel. Der Platz umh\u00fcllt den Spieler mit der nat\u00fcrlichen Umgebung der Insel. Dies und das Fehlen von Geb\u00e4uden entlang des Platzes sorgen f\u00fcr ein gro\u00dfartiges Golferlebnis. Ein komplettes Netz von Buggy-Pfaden verbindet alle L\u00f6cher miteinander.<\/p>\n<p>Der Golfpark Puntir\u00f3 wurde im April 2022 von T CLUB erworben. Der Platz wurde restauriert und in sein urspr\u00fcngliches Design mit \u00fcberarbeiteten Fairways, Bunkern, Wasserhindernissen und Gr\u00fcns gebracht. Wir haben &#8220;Piranya&#8221;-Gras gepflanzt, das als einer der besten Sorten der Welt f\u00fcr Golfgr\u00fcns gilt und das wir als erster Platz in Europa verwenden.<\/p>\n<p>Auch das Clubhaus wurde nach den hohen Standards vom T Club in T Golf Calvia renoviert.<\/p>\n","cta":{"ID":61695,"post_author":"4","post_date":"2025-08-25 12:19:54","post_date_gmt":"2025-08-25 12:19:54","post_content":"","post_title":"T Club \u2013 Angebot im Herbst","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"t-club-angebot-im-herbst-2","to_ping":"","pinged":"","post_modified":"2026-08-14 09:16:33","post_modified_gmt":"2026-08-14 09:16:33","post_content_filtered":"","post_parent":0,"guid":"https:\/\/t-golf.club\/?post_type=cta&#038;p=61695","menu_order":0,"post_type":"cta","post_mime_type":"","comment_count":"0","filter":"raw"},"video_large":"","features":[{"title":"Spielvorgaben","text":"<p><strong>Das Handicap und der Platz<\/strong><\/p>\n<p>Das Handicap, auch Stammvorgabe genannt, ber\u00fccksichtigt nicht die Schwierigkeit des Platzes. Die Spielvorgabe passt das Handicap dem jeweiligen Platz an. Je nach Schwierigkeitsgrad des Platzes kann ein Spieler mehr oder weniger Vorgabenschl\u00e4ge bekommen, als das reine Handicap zulassen w\u00fcrde. So wirkt sich ein herausfordernder Platz nicht zwingend schw\u00e4chend auf die Stammvorgabe aus. Anstatt zu trennen, erm\u00f6glichen diese Vorgaben es Spielern mit unterschiedlichen Spielerfahrungen auf Augenh\u00f6he ein faires Spiel gegeneinander zu spielen.<\/p>\n<p>Um unsere lokalen Platzregeln zu sehen, bitte <a class=\"w-40 mt-4 btn btn-primary\" href=\"\/wp-content\/uploads\/2022\/08\/LOCAL-RULES-ETTIQUETTE-T-GOLF-PALMA-DEU.pdf\" target=\"_blank\" rel=\"noopener\">HIER<\/a>Um Slope f\u00fcr Herren zu sehen, bitte <a class=\"w-40 mt-4 btn btn-primary\" href=\"https:\/\/t-golf.club\/wp-content\/uploads\/2024\/11\/BP15-1-T-GOLF-PALMA-HOMBRES.pdf\" target=\"_blank\" rel=\"noopener\">HIER<\/a>Um Slope f\u00fcr Damen zu sehen, bitte <a class=\"w-40 mt-4 btn btn-primary\" href=\"https:\/\/t-golf.club\/wp-content\/uploads\/2024\/11\/BP15-1-T-GOLF-PALMA-MUJERES.pdf\" target=\"_blank\" rel=\"noopener\">HIER<\/a>Um Slope f\u00fcr 9 L\u00f6cher zu sehen, bitte <a class=\"w-40 mt-4 btn btn-primary\" href=\"https:\/\/t-golf.club\/wp-content\/uploads\/2024\/11\/BP15-1-T-GOLF-PALMA-9-HOYOS.pdf\" target=\"_blank\" rel=\"noopener\">HIER<\/a><br \/>\nUm unsere Scorekarte zu sehen, klicken Sie bitte <a class=\"w-40 mt-4 btn btn-primary\" href=\"https:\/\/t-golf.club\/wp-content\/uploads\/2025\/03\/SCORE-CARD-PUNTIRO-2025.pdf\" target=\"_blank\" rel=\"noopener\">HIER<\/a><\/p>\n","link":"","images":[{"ID":16915,"id":16915,"title":"palma","filename":"palma.jpg","filesize":2587235,"url":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/palma.jpg","link":"https:\/\/t-golf.club\/de\/general-home\/palma-2\/","alt":"","author":"1","description":"","caption":"","name":"palma-2","status":"inherit","uploaded_to":16920,"date":"2022-08-23 09:38:57","modified":"2025-05-08 13:53:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/t-golf.club\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/palma-100x100.jpg","thumbnail-width":100,"thumbnail-height":100,"medium":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/palma-1024x683.jpg","medium-width":1024,"medium-height":683,"medium_large":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/palma-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/palma.jpg","large-width":1920,"large-height":1280,"1536x1536":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/palma-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/palma.jpg","2048x2048-width":1920,"2048x2048-height":1280}}]},{"title":"Driving Range","text":"<p class=\"\" data-start=\"42\" data-end=\"74\"><strong data-start=\"42\" data-end=\"74\">M\u00f6chten Sie ein wenig \u00fcben?<\/strong><\/p>\n<p class=\"\" data-start=\"76\" data-end=\"467\">Wir haben den perfekten Ort daf\u00fcr. Unsere Driving Range ist gut gepflegt, klar markiert, bietet verschiedene Ziele und ist gro\u00df genug, um gleichzeitig 50 Golfer zu beherbergen. F\u00fcr jeden Golfer ist das genau das, was man sich von einer Range w\u00fcnscht. Und, ach ja, wir haben auch noch die wundersch\u00f6ne mallorquinische Landschaft hinzugef\u00fcgt, denn bei T Golf geben wir immer ein bisschen mehr.<\/p>\n<p class=\"\" data-start=\"469\" data-end=\"654\">Unsere Trainingsgeb\u00fchr erm\u00f6glicht Ihnen die Nutzung der Driving Range sowie des Pitching- und Putting-Bereichs. Unsere Rangeb\u00e4lle sind Wilson Premium und haben keine Flugbeschr\u00e4nkungen.<\/p>\n<p class=\"\" data-start=\"656\" data-end=\"929\">Die Nutzung unserer \u00dcbungsanlagen ist bei Buchung eines 9- oder 18-Loch-Greenfees am selben Tag inklusive (exklusive Rangeb\u00e4lle). Wenn Sie ausschlie\u00dflich \u00fcben m\u00f6chten, betr\u00e4gt die Trainingsgeb\u00fchr 15\u202f\u20ac pro Person. Rangeb\u00e4lle werden separat berechnet \u2013 ein Token kostet 5\u202f\u20ac und enth\u00e4lt 30 B\u00e4lle<\/p>\n","link":"","images":[{"ID":70404,"id":70404,"title":"DR TGP 5","filename":"DR-TGP-5.jpg","filesize":829058,"url":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/04\/DR-TGP-5.jpg","link":"https:\/\/t-golf.club\/de\/palma\/golfplatz\/dr-tgp-5-2\/","alt":"","author":"268","description":"","caption":"","name":"dr-tgp-5-2","status":"inherit","uploaded_to":17000,"date":"2026-04-30 13:37:02","modified":"2026-04-30 13:38:56","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/t-golf.club\/wp-includes\/images\/media\/default.png","width":1841,"height":1257,"sizes":{"thumbnail":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/04\/DR-TGP-5-100x100.jpg","thumbnail-width":100,"thumbnail-height":100,"medium":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/04\/DR-TGP-5-1024x699.jpg","medium-width":1024,"medium-height":699,"medium_large":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/04\/DR-TGP-5-768x524.jpg","medium_large-width":768,"medium_large-height":524,"large":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/04\/DR-TGP-5.jpg","large-width":1841,"large-height":1257,"1536x1536":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/04\/DR-TGP-5-1536x1049.jpg","1536x1536-width":1536,"1536x1536-height":1049,"2048x2048":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/04\/DR-TGP-5.jpg","2048x2048-width":1841,"2048x2048-height":1257}}]},{"title":"Pitching & Putting Bereich","text":"<p>Das kurze Spiel ist einer der wichtigsten Bestandteile einer jeden Golfrunde. Wir m\u00f6chten sicherstellen, dass Sie Ihr Bestes geben. Deshalb haben wir viel Zeit und M\u00fche in die Schaffung eines neuen \u00dcbungsplatzes mit gro\u00dfen, gepflegten Putting Greens, Bunkern, Chipping- und Pitching-Zonen investiert.<\/p>\n","link":"","images":[{"ID":16977,"id":16977,"title":"GOLF PARK MALLORCA PUNTIRO - Hole 9 Green Bunkers - MR","filename":"GOLF-PARK-MALLORCA-PUNTIRO-Hole-9-Green-Bunkers-MR-scaled.jpg","filesize":768413,"url":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/GOLF-PARK-MALLORCA-PUNTIRO-Hole-9-Green-Bunkers-MR-scaled.jpg","link":"https:\/\/t-golf.club\/de\/palma\/golf-park-mallorca-puntiro-hole-9-green-bunkers-mr-2\/","alt":"","author":"275","description":"","caption":"","name":"golf-park-mallorca-puntiro-hole-9-green-bunkers-mr-2","status":"inherit","uploaded_to":16938,"date":"2022-08-23 15:53:32","modified":"2022-08-25 10:53:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/t-golf.club\/wp-includes\/images\/media\/default.png","width":2560,"height":1708,"sizes":{"thumbnail":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/GOLF-PARK-MALLORCA-PUNTIRO-Hole-9-Green-Bunkers-MR-100x100.jpg","thumbnail-width":100,"thumbnail-height":100,"medium":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/GOLF-PARK-MALLORCA-PUNTIRO-Hole-9-Green-Bunkers-MR-1024x683.jpg","medium-width":1024,"medium-height":683,"medium_large":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/GOLF-PARK-MALLORCA-PUNTIRO-Hole-9-Green-Bunkers-MR-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/GOLF-PARK-MALLORCA-PUNTIRO-Hole-9-Green-Bunkers-MR-2000x1334.jpg","large-width":2000,"large-height":1334,"1536x1536":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/GOLF-PARK-MALLORCA-PUNTIRO-Hole-9-Green-Bunkers-MR-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/GOLF-PARK-MALLORCA-PUNTIRO-Hole-9-Green-Bunkers-MR-2048x1366.jpg","2048x2048-width":2048,"2048x2048-height":1366}}]},{"title":"Halfway - Loch 10","text":"<p>Machen Sie auf halber Strecke eine wohlverdiente Pause an unserem Halfway direkt an Loch 10. St\u00e4rken Sie sich mit einem k\u00fchlen Getr\u00e4nk, einem Baguette oder einem Snack \u2014 bevor es mit frischer Energie in die zweiten Neun geht. In der Hochsaison (15. M\u00e4rz \u2013 15. Juni &amp; 1. September \u2013 15. November) t\u00e4glich ge\u00f6ffnet von 11:00 bis 16:00 Uhr. <em>\u00c4nderungen vorbehalten.<\/em><\/p>\n","link":"","images":[{"ID":70844,"id":70844,"title":"Halfway TGOLF PALMA","filename":"Halfway-TGOLF-PALMA.jpg","filesize":110401,"url":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/05\/Halfway-TGOLF-PALMA.jpg","link":"https:\/\/t-golf.club\/de\/palma\/golfplatz\/halfway-tgolf-palma-2\/","alt":"","author":"268","description":"","caption":"","name":"halfway-tgolf-palma-2","status":"inherit","uploaded_to":17000,"date":"2026-05-17 08:58:44","modified":"2026-05-17 08:58:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/t-golf.club\/wp-includes\/images\/media\/default.png","width":885,"height":550,"sizes":{"thumbnail":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/05\/Halfway-TGOLF-PALMA-100x100.jpg","thumbnail-width":100,"thumbnail-height":100,"medium":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/05\/Halfway-TGOLF-PALMA.jpg","medium-width":885,"medium-height":550,"medium_large":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/05\/Halfway-TGOLF-PALMA-768x477.jpg","medium_large-width":768,"medium_large-height":477,"large":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/05\/Halfway-TGOLF-PALMA.jpg","large-width":885,"large-height":550,"1536x1536":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/05\/Halfway-TGOLF-PALMA.jpg","1536x1536-width":885,"1536x1536-height":550,"2048x2048":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/05\/Halfway-TGOLF-PALMA.jpg","2048x2048-width":885,"2048x2048-height":550}}]},{"title":"Vermietungen","text":"<p>Vermietung von Clubs in T Golf Palma: TAYLORMADE<\/p>\n","link":{"title":"Zeig mehr","url":"http:\/\/t-golf.club\/de\/vermietungen\/","target":""},"images":[{"ID":17560,"id":17560,"title":"OLYMPUS DIGITAL CAMERA","filename":"2207-Palos-alquiler-TM2-LR.jpg","filesize":122031,"url":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/2207-Palos-alquiler-TM2-LR.jpg","link":"https:\/\/t-golf.club\/de\/vermietungen\/olympus-digital-camera-46-2\/","alt":"","author":"4","description":"","caption":"OLYMPUS DIGITAL CAMERA","name":"olympus-digital-camera-46-2","status":"inherit","uploaded_to":1532,"date":"2022-08-26 09:36:18","modified":"2022-08-26 09:36:18","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/t-golf.club\/wp-includes\/images\/media\/default.png","width":500,"height":666,"sizes":{"thumbnail":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/2207-Palos-alquiler-TM2-LR-100x100.jpg","thumbnail-width":100,"thumbnail-height":100,"medium":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/2207-Palos-alquiler-TM2-LR.jpg","medium-width":500,"medium-height":666,"medium_large":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/2207-Palos-alquiler-TM2-LR.jpg","medium_large-width":500,"medium_large-height":666,"large":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/2207-Palos-alquiler-TM2-LR.jpg","large-width":500,"large-height":666,"1536x1536":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/2207-Palos-alquiler-TM2-LR.jpg","1536x1536-width":500,"1536x1536-height":666,"2048x2048":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/2207-Palos-alquiler-TM2-LR.jpg","2048x2048-width":500,"2048x2048-height":666}}]},{"title":"Obligatorische Golf-Lizenz","text":"<p>Im T Club hat die Sicherheit und das Wohlbefinden aller, die unsere Einrichtungen nutzen, oberste Priorit\u00e4t. Zur Verst\u00e4rkung dieser Werte freuen wir uns, Ihnen eine wichtige Aktualisierung unserer Richtlinien f\u00fcr die Buchung von Startzeiten im T Club mitzuteilen, die ab dem 2. Februar 2026 in Kraft tritt.<\/p>\n<p>Ab diesem Datum ist es obligatorisch, f\u00fcr jede Buchung auf unseren Golfpl\u00e4tzen eine \u201eTages-Golf-Lizenz\u201c zu erwerben, es sei denn, die Spieler besitzen eine Lizenz der Spanischen Golf-Federation.<\/p>\n<p><a class=\"w-40 mt-4 btn btn-primary\" href=\"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/02\/Resumen-poliza_T-Golf-Palma_DE.pdf\" target=\"_blank\" rel=\"noopener\">Zusammenfassung<\/a><\/p>\n<p><a class=\"w-40 mt-4 btn btn-primary\" href=\"https:\/\/app.smartpanel.com\/crm\/NjIyIzE5OA==\/cform\/formulario-del-seguro-obligatorio-1?lang=de\" target=\"_blank\" rel=\"noopener\">PFLICHTFormular<\/a><\/p>\n<p>Obligatorische Golflizenz:<\/p>\n<ul>\n<li><strong>Lizenzierte Spieler:<\/strong> Wenn Sie eine Lizenz der Spanischen Golf-Federation besitzen, bitten wir Sie, Ihren g\u00fcltigen Mitgliedsnachweis vorzulegen. Diese Anforderung tr\u00e4gt dazu bei, eine sichere und gesch\u00fctzte Umgebung f\u00fcr alle Teilnehmer zu gew\u00e4hrleisten.<\/li>\n<li><strong>Nicht lizenzierte Spieler:<\/strong> F\u00fcr Spieler ohne Lizenz der Spanischen Golf-Federation ist es zwingend erforderlich, eine tempor\u00e4re Versicherung abzuschlie\u00dfen, um Zugang zu unseren Einrichtungen zu erhalten und daran teilzunehmen.<\/li>\n<\/ul>\n<p><strong>Der Preis betr\u00e4gt 3 \u20ac pro Tag und Person. <\/strong><\/p>\n<p>Diese Zahlung kann online bei der Buchung oder direkt in unseren Einrichtungen erfolgen.<\/p>\n<p><a class=\"w-40 mt-4 btn btn-primary\" href=\"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/02\/Haufig-gestellte-Fragen_Homepage_DE.pdf\" target=\"_blank\" rel=\"noopener\">Fragen<\/a><\/p>\n<p><a class=\"w-40 mt-4 btn btn-primary\" href=\"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/02\/Centros-concertados_pagina-web_TGP.pdf\" target=\"_blank\" rel=\"noopener\">vertragszentren<\/a><\/p>\n","link":"","images":[{"ID":66552,"id":66552,"title":"Academia FBG Foto cortada","filename":"Academia-FBG-Foto-cortada.jpg","filesize":26762,"url":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/02\/Academia-FBG-Foto-cortada.jpg","link":"https:\/\/t-golf.club\/de\/palma\/golfplatz\/academia-fbg-foto-cortada-2\/","alt":"","author":"268","description":"","caption":"","name":"academia-fbg-foto-cortada-2","status":"inherit","uploaded_to":17000,"date":"2026-02-09 07:38:07","modified":"2026-02-09 07:38:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/t-golf.club\/wp-includes\/images\/media\/default.png","width":643,"height":358,"sizes":{"thumbnail":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/02\/Academia-FBG-Foto-cortada-100x100.jpg","thumbnail-width":100,"thumbnail-height":100,"medium":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/02\/Academia-FBG-Foto-cortada.jpg","medium-width":643,"medium-height":358,"medium_large":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/02\/Academia-FBG-Foto-cortada.jpg","medium_large-width":643,"medium_large-height":358,"large":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/02\/Academia-FBG-Foto-cortada.jpg","large-width":643,"large-height":358,"1536x1536":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/02\/Academia-FBG-Foto-cortada.jpg","1536x1536-width":643,"1536x1536-height":358,"2048x2048":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/02\/Academia-FBG-Foto-cortada.jpg","2048x2048-width":643,"2048x2048-height":358}}]},{"title":"Hole-in-One Ehrungen","text":"<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Ein Hole-in-One ist eine der seltensten und beeindruckendsten Leistungen im Golfsport.<\/strong><\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Hier w\u00fcrdigen wir alle Spieler, die auf T Golf Palma ein Hole-in-One erzielt haben. Diese au\u00dfergew\u00f6hnliche Leistung verdient besondere Anerkennung und einen Platz in unserer Ehrengalerie.<\/p>\n","link":"","images":[{"ID":65590,"id":65590,"title":"Mateo Sastre_TGP_14.07.25","filename":"Mateo-Sastre_TGP_14.07.25.jpg","filesize":210331,"url":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/01\/Mateo-Sastre_TGP_14.07.25.jpg","link":"https:\/\/t-golf.club\/de\/palma\/golfplatz\/mateo-sastre_tgp_14-07-25-2\/","alt":"","author":"268","description":"","caption":"","name":"mateo-sastre_tgp_14-07-25-2","status":"inherit","uploaded_to":17000,"date":"2026-01-08 14:23:45","modified":"2026-01-08 14:23:56","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/t-golf.club\/wp-includes\/images\/media\/default.png","width":1200,"height":1600,"sizes":{"thumbnail":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/01\/Mateo-Sastre_TGP_14.07.25-100x100.jpg","thumbnail-width":100,"thumbnail-height":100,"medium":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/01\/Mateo-Sastre_TGP_14.07.25-768x1024.jpg","medium-width":768,"medium-height":1024,"medium_large":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/01\/Mateo-Sastre_TGP_14.07.25-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/01\/Mateo-Sastre_TGP_14.07.25.jpg","large-width":1200,"large-height":1600,"1536x1536":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/01\/Mateo-Sastre_TGP_14.07.25-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/01\/Mateo-Sastre_TGP_14.07.25.jpg","2048x2048-width":1200,"2048x2048-height":1600}},{"ID":65587,"id":65587,"title":"Elisabeth Carnbring_TGP_05.12.25","filename":"Elisabeth-Carnbring_TGP_05.12.25.jpg","filesize":98138,"url":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/01\/Elisabeth-Carnbring_TGP_05.12.25.jpg","link":"https:\/\/t-golf.club\/de\/palma\/golfplatz\/elisabeth-carnbring_tgp_05-12-25-2\/","alt":"","author":"268","description":"","caption":"","name":"elisabeth-carnbring_tgp_05-12-25-2","status":"inherit","uploaded_to":17000,"date":"2026-01-08 14:22:31","modified":"2026-01-08 14:22:31","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/t-golf.club\/wp-includes\/images\/media\/default.png","width":700,"height":771,"sizes":{"thumbnail":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/01\/Elisabeth-Carnbring_TGP_05.12.25-100x100.jpg","thumbnail-width":100,"thumbnail-height":100,"medium":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/01\/Elisabeth-Carnbring_TGP_05.12.25.jpg","medium-width":700,"medium-height":771,"medium_large":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/01\/Elisabeth-Carnbring_TGP_05.12.25.jpg","medium_large-width":700,"medium_large-height":771,"large":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/01\/Elisabeth-Carnbring_TGP_05.12.25.jpg","large-width":700,"large-height":771,"1536x1536":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/01\/Elisabeth-Carnbring_TGP_05.12.25.jpg","1536x1536-width":700,"1536x1536-height":771,"2048x2048":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/01\/Elisabeth-Carnbring_TGP_05.12.25.jpg","2048x2048-width":700,"2048x2048-height":771}},{"ID":69216,"id":69216,"title":"Gunnar Wexel_TGP_12.03.26","filename":"Gunnar-Wexel_TGP_12.03.26.jpg","filesize":203030,"url":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/03\/Gunnar-Wexel_TGP_12.03.26.jpg","link":"https:\/\/t-golf.club\/de\/palma\/golfplatz\/gunnar-wexel_tgp_12-03-26-2\/","alt":"","author":"268","description":"","caption":"","name":"gunnar-wexel_tgp_12-03-26-2","status":"inherit","uploaded_to":17000,"date":"2026-03-14 13:28:56","modified":"2026-03-14 13:30:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/t-golf.club\/wp-includes\/images\/media\/default.png","width":1500,"height":2000,"sizes":{"thumbnail":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/03\/Gunnar-Wexel_TGP_12.03.26-100x100.jpg","thumbnail-width":100,"thumbnail-height":100,"medium":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/03\/Gunnar-Wexel_TGP_12.03.26-768x1024.jpg","medium-width":768,"medium-height":1024,"medium_large":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/03\/Gunnar-Wexel_TGP_12.03.26-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/03\/Gunnar-Wexel_TGP_12.03.26.jpg","large-width":1500,"large-height":2000,"1536x1536":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/03\/Gunnar-Wexel_TGP_12.03.26-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/03\/Gunnar-Wexel_TGP_12.03.26.jpg","2048x2048-width":1500,"2048x2048-height":2000}}]},{"title":"Fauna und Vegetation","text":"<p class=\"font-claude-response-body break-words whitespace-normal\">T Golf Palma erstreckt sich in einer f\u00fcr das Inselinnere Mallorcas typischen Landschaft, in der weitl\u00e4ufige mediterranen Pinienw\u00e4lder und einheimische Vegetation sich mit Seen, naturnahen Zonen und offenen Fl\u00e4chen verbinden, die eine bemerkenswerte biologische Vielfalt beg\u00fcnstigen.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">Das Vorhandensein von Wasserfl\u00e4chen und gut erhaltenen Lebensr\u00e4umen macht den Platz zu einem ganzj\u00e4hrigen R\u00fcckzugsort f\u00fcr zahlreiche Vogelarten.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">Die Seen und naturnahen Bereiche dienen als Rast-, Nahrungs- und Brutpl\u00e4tze f\u00fcr eine Vielzahl von Stand- und Zugv\u00f6geln und machen T Golf Palma zu einer der artenreichsten Gr\u00fcnfl\u00e4chen im Umland von Palma.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">Zu den am h\u00e4ufigsten anzutreffenden Arten z\u00e4hlen verschiedene Entenarten, Reiher, G\u00e4nse, Bl\u00e4ssh\u00fchner und andere Wasserv\u00f6gel. In den Zugzeiten kommen zudem besonders interessante G\u00e4ste hinzu, wie etwa Flamingos, deren Anwesenheit zuletzt an den Seen der L\u00f6cher 8 und 15 beobachtet werden konnte. Fasane und Rebh\u00fchner finden in den ruhigeren Bereichen des Platzes Zuflucht, w\u00e4hrend Greifv\u00f6gel, insektenfressende V\u00f6gel und zahlreiche Best\u00e4uber zum nat\u00fcrlichen Gleichgewicht des \u00d6kosystems beitragen.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">Die Vegetation verbindet sorgf\u00e4ltig gepflegte Spielbereiche mit ausgedehnten mediterranen Pinienw\u00e4ldern, Wilds\u00f6lb\u00e4umen und einheimischem Buschwerk und schafft so eine Landschaft, die den nat\u00fcrlichen Charakter Mallorcas wahrt und jedem Loch seine besondere Pers\u00f6nlichkeit verleiht. Diese Pflanzenvielfalt f\u00f6rdert den Erhalt der Artenvielfalt, verbessert die landschaftliche Einbindung des Platzes und bietet der heimischen Tierwelt unverzichtbare Lebensr\u00e4ume.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">In T Golf Palma leben Golf und Natur in Einklang miteinander. Die verantwortungsvolle Bewirtschaftung der Naturfl\u00e4chen bewahrt den \u00f6kologischen Reichtum des Gel\u00e4ndes und bietet Spielern und Besuchern ein einzigartiges Erlebnis, bei dem die Qualit\u00e4t des Platzes durch die Sch\u00f6nheit und das Leben seiner Umgebung bereichert wird.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\"><strong>\u00dcber seine sportliche Exzellenz hinaus ist T Golf Palma ein kleines Biodiversit\u00e4tssanktuar, in dem mediterrane Landschaft, Wildtiere und Golf auf nat\u00fcrliche Weise miteinander verschmelzen und jede Golfrunde durch eine echte Verbindung zur Natur bereichern.<\/strong><\/p>\n","link":"","images":[{"ID":72107,"id":72107,"title":"TGP FF 2","filename":"TGP-FF-2.jpg","filesize":449051,"url":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/07\/TGP-FF-2.jpg","link":"https:\/\/t-golf.club\/de\/palma\/golfplatz\/tgp-ff-2-2\/","alt":"","author":"268","description":"","caption":"","name":"tgp-ff-2-2","status":"inherit","uploaded_to":17000,"date":"2026-07-03 08:45:28","modified":"2026-07-03 08:46:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/t-golf.club\/wp-includes\/images\/media\/default.png","width":750,"height":1334,"sizes":{"thumbnail":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/07\/TGP-FF-2-100x100.jpg","thumbnail-width":100,"thumbnail-height":100,"medium":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/07\/TGP-FF-2-576x1024.jpg","medium-width":576,"medium-height":1024,"medium_large":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/07\/TGP-FF-2.jpg","medium_large-width":750,"medium_large-height":1334,"large":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/07\/TGP-FF-2.jpg","large-width":750,"large-height":1334,"1536x1536":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/07\/TGP-FF-2.jpg","1536x1536-width":750,"1536x1536-height":1334,"2048x2048":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/07\/TGP-FF-2.jpg","2048x2048-width":750,"2048x2048-height":1334}}]},{"title":"Engagement f\u00fcr Nachhaltigkeit: Unsere neue Photovoltaikanlage bei T Golf Palma","text":"<p class=\"font-claude-response-body break-words whitespace-normal\">Bei T Golf Palma gehen wir einen entscheidenden Schritt in Richtung einer saubereren und verantwortungsvolleren Zukunft. Wir haben ein ambitioniertes Projekt f\u00fcr erneuerbare Energien an unserem Standort in Palma de Mallorca ins Leben gerufen.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\"><strong>Worum geht es bei dem Projekt?<\/strong><\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">Das Projekt umfasst die Planung und Installation einer netzgekoppelten Photovoltaikanlage mit 100 kW, die speziell f\u00fcr den Eigenverbrauch konzipiert wurde. Das System wurde effizient in die geneigten Ziegeld\u00e4cher eines der Hauptgeb\u00e4ude innerhalb des Golfplatzgel\u00e4ndes integriert.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\"><strong>Wichtigste technische Merkmale<\/strong><\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">Unsere Anlage setzt auf modernste Technologie, um eine maximale Energieausbeute zu gew\u00e4hrleisten:<\/p>\n<ul class=\"[li_&amp;]:mb-0 [li_&amp;]:mt-1 [li_&amp;]:gap-1 [&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc flex flex-col gap-1 pl-8 mb-3\">\n<li class=\"font-claude-response-body whitespace-normal break-words pl-2\"><strong>Installierte Leistung:<\/strong> Gesamte Panelleistung von 99,9 kWp.<\/li>\n<li class=\"font-claude-response-body whitespace-normal break-words pl-2\"><strong>Hochwertige Komponenten:<\/strong> Es wurden 222 Solarmodule der Marke RISEN (Modell 450 Wp) sowie ein hochmoderner Wechselrichter SMA Modell Core2 installiert, dessen Ausgangsleistung auf 100 kW begrenzt ist, um die Effizienz zu optimieren und die gesetzlichen Anforderungen zu erf\u00fcllen.<\/li>\n<li class=\"font-claude-response-body whitespace-normal break-words pl-2\"><strong>Gesch\u00e4tzte Produktion:<\/strong> Das System soll eine j\u00e4hrliche Erzeugung von ca. 136.179,27 kWh erzielen und dabei die Sonnenstunden Mallorcas optimal nutzen.<\/li>\n<li class=\"font-claude-response-body whitespace-normal break-words pl-2\"><strong>Garantierte Effizienz:<\/strong> Das System wurde so ausgelegt, dass es einen Gesamtwirkungsgrad von 73,26 % erreicht, wobei Faktoren wie die Dachneigung und die lokalen Temperaturen ber\u00fccksichtigt wurden.<\/li>\n<\/ul>\n<p class=\"font-claude-response-body break-words whitespace-normal\"><strong>Zweck und Vorteile<\/strong><\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">Das \u00fcbergeordnete Ziel dieser Investition ist die Umstellung auf ein nachhaltiges Energiemodell. Das Projekt st\u00fctzt sich auf drei S\u00e4ulen:<\/p>\n<ol class=\"[li_&amp;]:mb-0 [li_&amp;]:mt-1 [li_&amp;]:gap-1 [&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-decimal flex flex-col gap-1 pl-8 mb-3\">\n<li class=\"font-claude-response-body whitespace-normal break-words pl-2\"><strong>Effizienter Eigenverbrauch:<\/strong> Wir streben an, den Gro\u00dfteil unseres Energiebedarfs mit sauberer Energie zu decken, die direkt vor Ort erzeugt wird.<\/li>\n<li class=\"font-claude-response-body whitespace-normal break-words pl-2\"><strong>\u00dcberschussmanagement:<\/strong> Im Rahmen des Modells \u201eEigenverbrauch mit verg\u00fctetem \u00dcberschuss&#8221; wird jede erzeugte, aber nicht verbrauchte Energie in das konventionelle Stromnetz eingespeist, wof\u00fcr eine entsprechende finanzielle Verg\u00fctung gew\u00e4hrt wird.<\/li>\n<li class=\"font-claude-response-body whitespace-normal break-words pl-2\"><strong>Minimale Umweltbelastung:<\/strong> Das Projekt reduziert nicht nur unseren CO\u2082-Fu\u00dfabdruck, sondern wurde auch so geplant, dass bei der Umsetzung ein Minimum an Abfall anf\u00e4llt \u2013 in strikter \u00dcbereinstimmung mit den geltenden Umweltvorschriften.<\/li>\n<\/ol>\n<p class=\"font-claude-response-body break-words whitespace-normal\">Mit dieser Initiative bekr\u00e4ftigt T Golf Palma sein Engagement f\u00fcr den Schutz der Umwelt und bietet unseren Mitgliedern und G\u00e4sten einen Raum, der die Natur unserer Insel respektiert und bewahrt.<\/p>\n","link":"","images":[{"ID":71861,"id":71861,"title":"Foto Placas_TGP","filename":"Foto-Placas_TGP.jpg","filesize":74981,"url":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/06\/Foto-Placas_TGP.jpg","link":"https:\/\/t-golf.club\/de\/palma\/golfplatz\/foto-placas_tgp-2\/","alt":"","author":"268","description":"","caption":"","name":"foto-placas_tgp-2","status":"inherit","uploaded_to":17000,"date":"2026-06-25 08:02:45","modified":"2026-06-25 08:02:45","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/t-golf.club\/wp-includes\/images\/media\/default.png","width":660,"height":655,"sizes":{"thumbnail":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/06\/Foto-Placas_TGP-100x100.jpg","thumbnail-width":100,"thumbnail-height":100,"medium":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/06\/Foto-Placas_TGP.jpg","medium-width":660,"medium-height":655,"medium_large":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/06\/Foto-Placas_TGP.jpg","medium_large-width":660,"medium_large-height":655,"large":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/06\/Foto-Placas_TGP.jpg","large-width":660,"large-height":655,"1536x1536":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/06\/Foto-Placas_TGP.jpg","1536x1536-width":660,"1536x1536-height":655,"2048x2048":"https:\/\/t-golf.club\/wp-content\/uploads\/2026\/06\/Foto-Placas_TGP.jpg","2048x2048-width":660,"2048x2048-height":655}}]}],"wp_nav_image":false},"yoast_head":"<title>Golfplatz - T Golf Palma - T Golf<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/t-golf.club\/de\/palma\/golfplatz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Golfplatz - T Golf Palma - T Golf\" \/>\n<meta property=\"og:url\" content=\"https:\/\/t-golf.club\/de\/palma\/golfplatz\/\" \/>\n<meta property=\"og:site_name\" content=\"T Golf\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-14T09:31:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/GOLF-PARK-MALLORCA-PUNTIRO-Hole-9-Green-Bunkers-MR-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/t-golf.club\\\/de\\\/palma\\\/golfplatz\\\/\",\"url\":\"https:\\\/\\\/t-golf.club\\\/de\\\/palma\\\/golfplatz\\\/\",\"name\":\"Golfplatz - T Golf Palma - T Golf\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/t-golf.club\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/t-golf.club\\\/de\\\/palma\\\/golfplatz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/t-golf.club\\\/de\\\/palma\\\/golfplatz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/t-golf.club\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/GOLF-PARK-MALLORCA-PUNTIRO-Hole-9-Green-Bunkers-MR-scaled.jpg\",\"datePublished\":\"2022-08-25T10:47:44+00:00\",\"dateModified\":\"2026-08-14T09:31:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/t-golf.club\\\/de\\\/palma\\\/golfplatz\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/t-golf.club\\\/de\\\/palma\\\/golfplatz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/t-golf.club\\\/de\\\/palma\\\/golfplatz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/t-golf.club\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/GOLF-PARK-MALLORCA-PUNTIRO-Hole-9-Green-Bunkers-MR-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/t-golf.club\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/GOLF-PARK-MALLORCA-PUNTIRO-Hole-9-Green-Bunkers-MR-scaled.jpg\",\"width\":2560,\"height\":1708},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/t-golf.club\\\/de\\\/palma\\\/golfplatz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/t-golf.club\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home &#8211; Palma\",\"item\":\"https:\\\/\\\/t-golf.club\\\/de\\\/palma\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Golfplatz &#8211; T Golf Palma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/t-golf.club\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/t-golf.club\\\/de\\\/\",\"name\":\"T Golf\",\"description\":\"\",\"inLanguage\":\"de-DE\"}]}<\/script>","yoast_head_json":{"title":"Golfplatz - T Golf Palma - T Golf","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/t-golf.club\/de\/palma\/golfplatz\/","og_locale":"de_DE","og_type":"article","og_title":"Golfplatz - T Golf Palma - T Golf","og_url":"https:\/\/t-golf.club\/de\/palma\/golfplatz\/","og_site_name":"T Golf","article_modified_time":"2026-08-14T09:31:31+00:00","og_image":[{"width":2560,"height":1708,"url":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/GOLF-PARK-MALLORCA-PUNTIRO-Hole-9-Green-Bunkers-MR-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/t-golf.club\/de\/palma\/golfplatz\/","url":"https:\/\/t-golf.club\/de\/palma\/golfplatz\/","name":"Golfplatz - T Golf Palma - T Golf","isPartOf":{"@id":"https:\/\/t-golf.club\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/t-golf.club\/de\/palma\/golfplatz\/#primaryimage"},"image":{"@id":"https:\/\/t-golf.club\/de\/palma\/golfplatz\/#primaryimage"},"thumbnailUrl":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/GOLF-PARK-MALLORCA-PUNTIRO-Hole-9-Green-Bunkers-MR-scaled.jpg","datePublished":"2022-08-25T10:47:44+00:00","dateModified":"2026-08-14T09:31:31+00:00","breadcrumb":{"@id":"https:\/\/t-golf.club\/de\/palma\/golfplatz\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/t-golf.club\/de\/palma\/golfplatz\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/t-golf.club\/de\/palma\/golfplatz\/#primaryimage","url":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/GOLF-PARK-MALLORCA-PUNTIRO-Hole-9-Green-Bunkers-MR-scaled.jpg","contentUrl":"https:\/\/t-golf.club\/wp-content\/uploads\/2022\/08\/GOLF-PARK-MALLORCA-PUNTIRO-Hole-9-Green-Bunkers-MR-scaled.jpg","width":2560,"height":1708},{"@type":"BreadcrumbList","@id":"https:\/\/t-golf.club\/de\/palma\/golfplatz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/t-golf.club\/de\/"},{"@type":"ListItem","position":2,"name":"Home &#8211; Palma","item":"https:\/\/t-golf.club\/de\/palma\/"},{"@type":"ListItem","position":3,"name":"Golfplatz &#8211; T Golf Palma"}]},{"@type":"WebSite","@id":"https:\/\/t-golf.club\/de\/#website","url":"https:\/\/t-golf.club\/de\/","name":"T Golf","description":"","inLanguage":"de-DE"}]}},"_links":{"self":[{"href":"https:\/\/t-golf.club\/de\/wp-json\/wp\/v2\/pages\/17000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/t-golf.club\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/t-golf.club\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/t-golf.club\/de\/wp-json\/wp\/v2\/users\/275"}],"replies":[{"embeddable":true,"href":"https:\/\/t-golf.club\/de\/wp-json\/wp\/v2\/comments?post=17000"}],"version-history":[{"count":17,"href":"https:\/\/t-golf.club\/de\/wp-json\/wp\/v2\/pages\/17000\/revisions"}],"predecessor-version":[{"id":73246,"href":"https:\/\/t-golf.club\/de\/wp-json\/wp\/v2\/pages\/17000\/revisions\/73246"}],"up":[{"embeddable":true,"href":"https:\/\/t-golf.club\/de\/wp-json\/wp\/v2\/pages\/16938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/t-golf.club\/de\/wp-json\/wp\/v2\/media\/16977"}],"wp:attachment":[{"href":"https:\/\/t-golf.club\/de\/wp-json\/wp\/v2\/media?parent=17000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}